
{"id":34322,"count":173,"description":"","link":"https:\/\/www.californiapsychics.com\/blog\/authors\/juliet-demarco","name":"Juliet DeMarco","slug":"juliet-demarco","taxonomy":"cp_author","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Juliet DeMarco | California Psychics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.californiapsychics.com\/blog\/authors\/juliet-demarco\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juliet DeMarco | California Psychics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.californiapsychics.com\/blog\/authors\/juliet-demarco\" \/>\n<meta property=\"og:site_name\" content=\"California Psychics\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.californiapsychics.com\/blog\/authors\/juliet-demarco\",\"url\":\"https:\/\/www.californiapsychics.com\/blog\/authors\/juliet-demarco\",\"name\":\"Juliet DeMarco | California Psychics\",\"isPartOf\":{\"@id\":\"https:\/\/www.californiapsychics.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.californiapsychics.com\/blog\/authors\/juliet-demarco#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.californiapsychics.com\/blog\/#website\",\"url\":\"https:\/\/www.californiapsychics.com\/blog\/\",\"name\":\"California Psychics\",\"description\":\"Psychic Readings | Live Phone Psychics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.californiapsychics.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juliet DeMarco | California Psychics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.californiapsychics.com\/blog\/authors\/juliet-demarco","og_locale":"en_US","og_type":"article","og_title":"Juliet DeMarco | California Psychics","og_url":"https:\/\/www.californiapsychics.com\/blog\/authors\/juliet-demarco","og_site_name":"California Psychics","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.californiapsychics.com\/blog\/authors\/juliet-demarco","url":"https:\/\/www.californiapsychics.com\/blog\/authors\/juliet-demarco","name":"Juliet DeMarco | California Psychics","isPartOf":{"@id":"https:\/\/www.californiapsychics.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.californiapsychics.com\/blog\/authors\/juliet-demarco#breadcrumb"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/www.californiapsychics.com\/blog\/#website","url":"https:\/\/www.californiapsychics.com\/blog\/","name":"California Psychics","description":"Psychic Readings | Live Phone Psychics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.californiapsychics.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.californiapsychics.com\/blog\/wp-json\/wp\/v2\/cp_author\/34322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.californiapsychics.com\/blog\/wp-json\/wp\/v2\/cp_author"}],"about":[{"href":"https:\/\/www.californiapsychics.com\/blog\/wp-json\/wp\/v2\/taxonomies\/cp_author"}],"wp:post_type":[{"href":"https:\/\/www.californiapsychics.com\/blog\/wp-json\/wp\/v2\/posts?cp_author=34322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}